{"id":2019,"date":"2018-10-04T11:54:38","date_gmt":"2018-10-04T11:54:38","guid":{"rendered":"http:\/\/grupovna.com\/?post_type=product&#038;p=2019"},"modified":"2025-08-29T09:19:51","modified_gmt":"2025-08-29T09:19:51","slug":"posicionamiento","status":"publish","type":"product","link":"https:\/\/grupovna.com\/index.php\/product\/posicionamiento\/","title":{"rendered":"AUXILIAR VETERINARIO"},"content":{"rendered":"<p>Este curso capacita para adquirir los conocimientos y habilidades necesarias para ayudar y reforzar las labores profesionales de un veterinario en todos los departamentos de un hospital veterinario, estando destinado a cualquier persona, mayor de 16 a\u00f1os, que le gusten los animales y que desee trabajar en un centro veterinario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este curso capacita para adquirir los conocimientos y habilidades necesarias para ayudar y reforzar las labores profesionales de un veterinario en todos los departamentos de un hospital veterinario, estando destinado a cualquier persona, mayor de 16 a\u00f1os, que le gusten los animales y que desee trabajar en un centro veterinario.<\/p>\n","protected":false},"featured_media":2228,"comment_status":"open","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AUXILIAR VETERINARIO - GRUPO VNA LEVANTE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupovna.com\/index.php\/product\/posicionamiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AUXILIAR VETERINARIO - GRUPO VNA LEVANTE\" \/>\n<meta property=\"og:description\" content=\"Este curso capacita para adquirir los conocimientos y habilidades necesarias para ayudar y reforzar las labores profesionales de un veterinario en todos los departamentos de un hospital veterinario, estando destinado a cualquier persona, mayor de 16 a\u00f1os, que le gusten los animales y que desee trabajar en un centro veterinario.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupovna.com\/index.php\/product\/posicionamiento\/\" \/>\n<meta property=\"og:site_name\" content=\"GRUPO VNA LEVANTE\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T09:19:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupovna.com\/wp-content\/uploads\/2018\/10\/img-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/grupovna.com\/#website\",\"url\":\"https:\/\/grupovna.com\/\",\"name\":\"GRUPO VNA LEVANTE\",\"description\":\"Pymes, Autonomos, Universitarios, Formaci\\u00f3n Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/grupovna.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/grupovna.com\/index.php\/product\/posicionamiento\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/grupovna.com\/wp-content\/uploads\/2018\/10\/img-2.jpg\",\"width\":360,\"height\":240},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/grupovna.com\/index.php\/product\/posicionamiento\/#webpage\",\"url\":\"https:\/\/grupovna.com\/index.php\/product\/posicionamiento\/\",\"name\":\"AUXILIAR VETERINARIO - GRUPO VNA LEVANTE\",\"isPartOf\":{\"@id\":\"https:\/\/grupovna.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/grupovna.com\/index.php\/product\/posicionamiento\/#primaryimage\"},\"datePublished\":\"2018-10-04T11:54:38+00:00\",\"dateModified\":\"2025-08-29T09:19:51+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/grupovna.com\/index.php\/product\/posicionamiento\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/grupovna.com\/index.php\/wp-json\/wp\/v2\/product\/2019"}],"collection":[{"href":"https:\/\/grupovna.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/grupovna.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/grupovna.com\/index.php\/wp-json\/wp\/v2\/comments?post=2019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupovna.com\/index.php\/wp-json\/wp\/v2\/media\/2228"}],"wp:attachment":[{"href":"https:\/\/grupovna.com\/index.php\/wp-json\/wp\/v2\/media?parent=2019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}